{"id":6124,"date":"2024-03-14T14:24:55","date_gmt":"2024-03-14T14:24:55","guid":{"rendered":"https:\/\/cbdoileurope.com\/?page_id=6124"},"modified":"2024-03-14T14:24:55","modified_gmt":"2024-03-14T14:24:55","slug":"custom-gummies","status":"publish","type":"page","link":"https:\/\/cbdoileurope.com\/fr\/produits-cbd\/gommes-de-cbd\/gommes-personnalisees\/","title":{"rendered":"Gummies personnalis\u00e9s"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6124\" class=\"elementor elementor-6124\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46edf04e elementor-section-full_width elementor-section-height-min-height elementor-section-items-top elementor-section-height-default\" data-id=\"46edf04e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29ef533f\" data-id=\"29ef533f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6596e066 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6596e066\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-23e93507\" data-id=\"23e93507\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e0021d7 elementor-widget elementor-widget-woocommerce-breadcrumb\" data-id=\"2e0021d7\" data-element_type=\"widget\" data-widget_type=\"woocommerce-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"woocommerce-breadcrumb\" data-no-translation=\"\" data-trp-gettext=\"\">Accueil<\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-61680547 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"61680547\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4b2b3776\" data-id=\"4b2b3776\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40c4da02 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"40c4da02\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;curve&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,97C126.7,96.3,0.8,19.8,0,0v100l1000,0V1C1000,19.4,873.3,97.8,500,97z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4aa659fd\" data-id=\"4aa659fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a60c79 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1a60c79\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Formule unique<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Service personnalis\u00e9 complet<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36466258 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"36466258\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35e81994\" data-id=\"35e81994\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3df00406 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3df00406\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7d648b65\" data-id=\"7d648b65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-387eb930 elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"387eb930\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Gummies personnalis\u00e9s<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2d0c43 elementor-widget elementor-widget-heading\" data-id=\"3d2d0c43\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Personnalisez les ingr\u00e9dients, la forme, la couleur et le go\u00fbt de vos gommes.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d08ce11 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"7d08ce11\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-1024x1024.jpg\" class=\"attachment-large size-large wp-image-6453\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-1024x1024.jpg 1024w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-300x300.jpg 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-150x150.jpg 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-768x768.jpg 768w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-700x700.jpg 700w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-600x600.jpg 600w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-100x100.jpg 100w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap.jpg 1440w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c84dc18\" data-id=\"6c84dc18\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d470023 elementor-widget elementor-widget-text-editor\" data-id=\"2d470023\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les gommes sont le v\u00e9hicule id\u00e9al pour l'absorption d'ingr\u00e9dients actifs. Les gommes sont faciles \u00e0 prendre et les gens les associent \u00e0 la joie et aux moments heureux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15988fba elementor-widget elementor-widget-heading\" data-id=\"15988fba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment puis-je d\u00e9velopper un chewing-gum personnalis\u00e9 ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10dba762 elementor-widget elementor-widget-text-editor\" data-id=\"10dba762\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les co\u00fbts de d\u00e9veloppement d'une gomme unique s'\u00e9l\u00e8vent \u00e0 800 euros par UGS. Nous \u00e9tablissons une formulation unique pour votre entreprise, sur la base de vos besoins et de vos souhaits. Les frais de d\u00e9veloppement sont cr\u00e9dit\u00e9s sur votre compte lorsque vous passez une commande de 1000 unit\u00e9s ou plus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-248d620 elementor-widget elementor-widget-heading\" data-id=\"248d620\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">All\u00e9gations \/ effets cibl\u00e9s sur la sant\u00e9<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e831d6c elementor-widget elementor-widget-text-editor\" data-id=\"e831d6c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Avant de choisir l'ingr\u00e9dient actif, nous \u00e9tablissons les revendications ou les effets que votre gomme doit produire. Les all\u00e9gations sont associ\u00e9es \u00e0 une certaine quantit\u00e9 d'ingr\u00e9dient actif par portion. L'EFSA europ\u00e9enne (ou la FSA pour le Royaume-Uni) tient \u00e0 jour une base de donn\u00e9es des all\u00e9gations et des ingr\u00e9dients.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f40ac9d elementor-widget elementor-widget-heading\" data-id=\"f40ac9d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ingr\u00e9dients<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e75d67 elementor-widget elementor-widget-text-editor\" data-id=\"2e75d67\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En tenant compte des all\u00e9gations cibl\u00e9es, les d\u00e9veloppements commencent par d\u00e9finir l'objectif du projet. Exemple : \"gomme contenant la dose journali\u00e8re recommand\u00e9e de spiruline en 3 portions\". En moyenne, 500 mg d'ingr\u00e9dient actif peuvent \u00eatre m\u00e9lang\u00e9s dans une gomme de 2,5 grammes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37c663f6 elementor-widget elementor-widget-heading\" data-id=\"37c663f6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Normes de qualit\u00e9<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43db0ba elementor-widget elementor-widget-text-editor\" data-id=\"43db0ba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous sommes fiers d'annoncer notre certification BPF Codex Alimentarius pour la production de chewing-gums. Nous poss\u00e9dons les accr\u00e9ditations ISO 9001:2015 et HACCP.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a387725 elementor-widget elementor-widget-gallery\" data-id=\"3a387725\" data-element_type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;justified&quot;,&quot;ideal_row_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:90,&quot;sizes&quot;:[]},&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;ideal_row_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:90,&quot;sizes&quot;:[]},&quot;ideal_row_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:80,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]}}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-GMP-v1-1-150x150.webp\" data-width=\"150\" data-height=\"150\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-HACCP-v1-1-150x150.webp\" data-width=\"150\" data-height=\"150\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1-150x150.webp\" data-width=\"150\" data-height=\"150\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EU-v1-1-150x150.webp\" data-width=\"150\" data-height=\"150\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ccd44f9 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"1ccd44f9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/cbdoileurope.com\/fr\/a-propos-de\/qualite-et-conformite\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68517252 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"68517252\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5cb15fe6\" data-id=\"5cb15fe6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4c804752 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c804752\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4003fb08\" data-id=\"4003fb08\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c5afc19 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7c5afc19\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-pure-cbd-1024x1024.jpg\" class=\"attachment-large size-large wp-image-5209\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-pure-cbd-1024x1024.jpg 1024w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-pure-cbd-300x300.jpg 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-pure-cbd-150x150.jpg 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-pure-cbd-768x768.jpg 768w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-pure-cbd-700x700.jpg 700w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-pure-cbd-600x600.jpg 600w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-pure-cbd-100x100.jpg 100w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-pure-cbd.jpg 1440w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\">CBD pur<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5abce371 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5abce371\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-broad-spectrum-2-1024x1024.jpg\" class=\"attachment-large size-large wp-image-5202\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-broad-spectrum-2-1024x1024.jpg 1024w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-broad-spectrum-2-300x300.jpg 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-broad-spectrum-2-150x150.jpg 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-broad-spectrum-2-768x768.jpg 768w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-broad-spectrum-2-700x700.jpg 700w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-broad-spectrum-2-600x600.jpg 600w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-broad-spectrum-2-100x100.jpg 100w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-broad-spectrum-2.jpg 1440w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\">Large spectre<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00c2596 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"00c2596\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-laboratory-tested-1024x1024.jpg\" class=\"attachment-large size-large wp-image-5208\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-laboratory-tested-1024x1024.jpg 1024w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-laboratory-tested-300x300.jpg 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-laboratory-tested-150x150.jpg 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-laboratory-tested-768x768.jpg 768w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-laboratory-tested-700x700.jpg 700w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-laboratory-tested-600x600.jpg 600w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-laboratory-tested-100x100.jpg 100w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-laboratory-tested.jpg 1440w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\">Test\u00e9 en laboratoire<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31a7d5c5 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"31a7d5c5\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-vegan-friendly-1024x1024.jpg\" class=\"attachment-large size-large wp-image-5211\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-vegan-friendly-1024x1024.jpg 1024w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-vegan-friendly-300x300.jpg 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-vegan-friendly-150x150.jpg 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-vegan-friendly-768x768.jpg 768w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-vegan-friendly-700x700.jpg 700w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-vegan-friendly-600x600.jpg 600w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-vegan-friendly-100x100.jpg 100w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-vegan-friendly.jpg 1440w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\">Convient aux v\u00e9g\u00e9tariens<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55de1358 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"55de1358\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-gmo-free-1024x1024.jpg\" class=\"attachment-large size-large wp-image-5207\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-gmo-free-1024x1024.jpg 1024w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-gmo-free-300x300.jpg 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-gmo-free-150x150.jpg 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-gmo-free-768x768.jpg 768w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-gmo-free-700x700.jpg 700w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-gmo-free-600x600.jpg 600w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-gmo-free-100x100.jpg 100w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-icon-gmo-free.jpg 1440w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\">Sans OGM<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-edfad8c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edfad8c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4d403f36\" data-id=\"4d403f36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-415782ac elementor-widget elementor-widget-heading\" data-id=\"415782ac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Options des produits<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51ffa044 elementor-widget elementor-widget-heading\" data-id=\"51ffa044\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9veloppement de gommes sur mesure<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36a4302c elementor-widget elementor-widget-text-editor\" data-id=\"36a4302c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous proposons un certain nombre de choix pour le d\u00e9veloppement de votre gomme personnalis\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-306012de elementor-widget elementor-widget-tp-accordion\" data-id=\"306012de\" data-element_type=\"widget\" data-widget_type=\"tp-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"theplus-accordion-wrapper elementor-accordion\" id=\"accordion6a04959bd372d\" data-accordion-id=\"accordion6a04959bd372d\" data-connection=\"\" data-accordion-type=\"accordion\" data-heightlight-text role=\"tablist\" > \r\n\t\t\r\n\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-8111\" class=\"elementor-tab-title plus-accordion-header active-default text-left\" data-tab=\"1\" aria-controls=\"elementor-tab-content-8111\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\r\n\t\t\t\t\t\t<span style=\"width:100%\">Saveur<\/span>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-8111\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content active-default\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8111\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>L'ingr\u00e9dient actif joue ici un r\u00f4le important. Si l'ingr\u00e9dient actif a un go\u00fbt, l'ar\u00f4me doit \u00eatre compl\u00e9mentaire. Nous jouons un r\u00f4le actif, si n\u00e9cessaire, dans cette phase du d\u00e9veloppement.<\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-8112\" class=\"elementor-tab-title plus-accordion-header no text-left\" data-tab=\"2\" aria-controls=\"elementor-tab-content-8112\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\r\n\t\t\t\t\t\t<span style=\"width:100%\">Couleur<\/span>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-8112\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8112\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>Les colorants alimentaires naturels peuvent \u00eatre utilis\u00e9s pour donner la couleur souhait\u00e9e \u00e0 une gomme. Si l'ingr\u00e9dient actif et l'ar\u00f4me colorent d\u00e9j\u00e0 la gomme, cela influence le r\u00e9sultat final. Une gomme claire peut \u00eatre rendue diff\u00e9rente ou plus fonc\u00e9e par l'ajout de colorants.<\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-8113\" class=\"elementor-tab-title plus-accordion-header no text-left\" data-tab=\"3\" aria-controls=\"elementor-tab-content-8113\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\r\n\t\t\t\t\t\t<span style=\"width:100%\">Forme<\/span>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-8113\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8113\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>Pour les gommes de forme unique, nous concevons et commandons des moules sur mesure si n\u00e9cessaire. Le moulage de nouveaux moules entra\u00eene des frais uniques d'environ 4 000 euros.<\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-8114\" class=\"elementor-tab-title plus-accordion-header no text-left\" data-tab=\"4\" aria-controls=\"elementor-tab-content-8114\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\r\n\t\t\t\t\t\t<span style=\"width:100%\">\u00c9chantillons<\/span>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-8114\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8114\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>Une fois que nous avons d\u00e9cid\u00e9 et approuv\u00e9 notre cahier des charges commun, nous commen\u00e7ons \u00e0 acheter les ingr\u00e9dients n\u00e9cessaires et \u00e0 planifier la production de votre premier lot d'\u00e9chantillons. Nous exp\u00e9rimentons jusqu'\u00e0 ce que la recette soit stable, puis nous produisons des \u00e9chantillons que vous pouvez essayer. En fonction des d\u00e9lais de livraison des ingr\u00e9dients uniques, ce processus prend entre 3 et 6 semaines.<\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-8115\" class=\"elementor-tab-title plus-accordion-header no text-left\" data-tab=\"5\" aria-controls=\"elementor-tab-content-8115\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\r\n\t\t\t\t\t\t<span style=\"width:100%\">Cycle de retour d'information<\/span>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-8115\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8115\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>Apr\u00e8s avoir essay\u00e9 nos \u00e9chantillons, nous organisons une s\u00e9ance de retour d'information. Nous discutons de vos r\u00e9actions et de vos commentaires, et nous \u00e9laborons un cahier des charges final. La recette sera adapt\u00e9e en fonction des commentaires.<\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-8116\" class=\"elementor-tab-title plus-accordion-header no text-left\" data-tab=\"6\" aria-controls=\"elementor-tab-content-8116\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\r\n\t\t\t\t\t\t<span style=\"width:100%\">\u00c9chantillons finaux<\/span>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-8116\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8116\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>Apr\u00e8s avoir ajust\u00e9 la recette en fonction des commentaires re\u00e7us, nous planifions la production des \u00e9chantillons finaux. Ces \u00e9chantillons vous sont envoy\u00e9s pour r\u00e9f\u00e9rence et constituent la base de votre commande.<\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-8117\" class=\"elementor-tab-title plus-accordion-header no text-left\" data-tab=\"7\" aria-controls=\"elementor-tab-content-8117\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\r\n\t\t\t\t\t\t<span style=\"width:100%\">Sans sucre<\/span>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-8117\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-8117\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>Les gommes peuvent \u00eatre d\u00e9velopp\u00e9es en rempla\u00e7ant le sucre par du maltitol. <\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\r\n\t\t<\/div>  \r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4d5919c\" data-id=\"4d5919c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7232608 elementor-widget elementor-widget-video\" data-id=\"7232608\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/05\/Fruit-mix-gummies.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" playsinline=\"\" controlslist=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c5cfd46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c5cfd46\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3c53319b\" data-id=\"3c53319b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba2324c elementor-widget elementor-widget-gallery\" data-id=\"ba2324c\" data-element_type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns_tablet&quot;:3,&quot;columns_mobile&quot;:2,&quot;columns&quot;:4,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4785_cherry_gummies_sweet_sour.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"IMG_4785_cherry_gummies_sweet_sour\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQzNCwidXJsIjoiaHR0cHM6XC9cL2NiZG9pbGV1cm9wZS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9JTUdfNDc4NV9jaGVycnlfZ3VtbWllc19zd2VldF9zb3VyLmpwZyIsInNsaWRlc2hvdyI6ImJhMjMyNGMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4785_cherry_gummies_sweet_sour-768x768.jpg\" data-width=\"768\" data-height=\"768\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/11\/CBD-Services-PrivateLabel-HerbalSupplements-v1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"CBD-Services-PrivateLabel-HerbalSupplements-v1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTcyNTksInVybCI6Imh0dHBzOlwvXC9jYmRvaWxldXJvcGUuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8xMVwvQ0JELVNlcnZpY2VzLVByaXZhdGVMYWJlbC1IZXJiYWxTdXBwbGVtZW50cy12MS5qcGciLCJzbGlkZXNob3ciOiJiYTIzMjRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/11\/CBD-Services-PrivateLabel-HerbalSupplements-v1-768x432.jpg\" data-width=\"768\" data-height=\"432\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4841_lemon_gummies_with_fruit.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"IMG_4841_lemon_gummies_with_fruit\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQwNywidXJsIjoiaHR0cHM6XC9cL2NiZG9pbGV1cm9wZS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9JTUdfNDg0MV9sZW1vbl9ndW1taWVzX3dpdGhfZnJ1aXQuanBnIiwic2xpZGVzaG93IjoiYmEyMzI0YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4841_lemon_gummies_with_fruit-768x768.jpg\" data-width=\"768\" data-height=\"768\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/01\/Curcumin-oil-Tumeric-root.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"Curcumin-oil-Tumeric-root\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg5NiwidXJsIjoiaHR0cHM6XC9cL2NiZG9pbGV1cm9wZS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzAxXC9DdXJjdW1pbi1vaWwtVHVtZXJpYy1yb290LndlYnAiLCJzbGlkZXNob3ciOiJiYTIzMjRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/01\/Curcumin-oil-Tumeric-root.webp\" data-width=\"640\" data-height=\"486\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4248_custom_gummies-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"IMG_4248_custom_gummies\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQ1NCwidXJsIjoiaHR0cHM6XC9cL2NiZG9pbGV1cm9wZS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9JTUdfNDI0OF9jdXN0b21fZ3VtbWllcy0xLmpwZyIsInNsaWRlc2hvdyI6ImJhMjMyNGMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4248_custom_gummies-1-768x768.jpg\" data-width=\"768\" data-height=\"768\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4780_30gummies_jar_black_cap.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"IMG_4780_30gummies_jar_black_cap\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQwNCwidXJsIjoiaHR0cHM6XC9cL2NiZG9pbGV1cm9wZS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9JTUdfNDc4MF8zMGd1bW1pZXNfamFyX2JsYWNrX2NhcC5qcGciLCJzbGlkZXNob3ciOiJiYTIzMjRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4780_30gummies_jar_black_cap-768x768.jpg\" data-width=\"768\" data-height=\"768\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-Services-Herbal-Supplements-Ginger.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"CBD-Services-Herbal-Supplements-Ginger\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTc0NDMsInVybCI6Imh0dHBzOlwvXC9jYmRvaWxldXJvcGUuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvQ0JELVNlcnZpY2VzLUhlcmJhbC1TdXBwbGVtZW50cy1HaW5nZXIuanBnIiwic2xpZGVzaG93IjoiYmEyMzI0YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-Services-Herbal-Supplements-Ginger-768x768.jpg\" data-width=\"768\" data-height=\"768\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4110_jar_seal.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"IMG_4110_jar_seal\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQwNiwidXJsIjoiaHR0cHM6XC9cL2NiZG9pbGV1cm9wZS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9JTUdfNDExMF9qYXJfc2VhbC5qcGciLCJzbGlkZXNob3ciOiJiYTIzMjRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4110_jar_seal-768x768.jpg\" data-width=\"768\" data-height=\"768\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_pouch_craft_gummies.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"IMG_pouch_craft_gummies\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQ1NSwidXJsIjoiaHR0cHM6XC9cL2NiZG9pbGV1cm9wZS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9JTUdfcG91Y2hfY3JhZnRfZ3VtbWllcy5qcGciLCJzbGlkZXNob3ciOiJiYTIzMjRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_pouch_craft_gummies-768x768.jpg\" data-width=\"768\" data-height=\"768\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4857_fruit_mix_gummies_with_fruit-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"IMG_4857_fruit_mix_gummies_with_fruit\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQxMSwidXJsIjoiaHR0cHM6XC9cL2NiZG9pbGV1cm9wZS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9JTUdfNDg1N19mcnVpdF9taXhfZ3VtbWllc193aXRoX2ZydWl0LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiJiYTIzMjRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4857_fruit_mix_gummies_with_fruit-768x512.jpg\" data-width=\"768\" data-height=\"512\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4778_30gummies_jar_white_cap.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"IMG_4778_30gummies_jar_white_cap\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQwMywidXJsIjoiaHR0cHM6XC9cL2NiZG9pbGV1cm9wZS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjNcLzA0XC9JTUdfNDc3OF8zMGd1bW1pZXNfamFyX3doaXRlX2NhcC5qcGciLCJzbGlkZXNob3ciOiJiYTIzMjRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4778_30gummies_jar_white_cap-768x768.jpg\" data-width=\"768\" data-height=\"768\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-Services-Herbal-Supplements-Chamomile.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ba2324c\" data-elementor-lightbox-title=\"CBD-Services-Herbal-Supplements-Chamomile\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTc0MzUsInVybCI6Imh0dHBzOlwvXC9jYmRvaWxldXJvcGUuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvQ0JELVNlcnZpY2VzLUhlcmJhbC1TdXBwbGVtZW50cy1DaGFtb21pbGUuanBnIiwic2xpZGVzaG93IjoiYmEyMzI0YyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/03\/CBD-Services-Herbal-Supplements-Chamomile-768x768.jpg\" data-width=\"768\" data-height=\"768\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cac3da7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2cac3da7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34270a17\" data-id=\"34270a17\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62cae46e elementor-widget elementor-widget-template\" data-id=\"62cae46e\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"17598\" class=\"elementor elementor-17598\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28b311b5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"28b311b5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49605234\" data-id=\"49605234\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1b60d785 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b60d785\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-197eb747\" data-id=\"197eb747\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63d7efae elementor-widget elementor-widget-heading\" data-id=\"63d7efae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quemment pos\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12012893 elementor-align-left elementor-tablet-align-center elementor-widget-tablet__width-inherit elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"12012893\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/cbdoileurope.com\/fr\/docs\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir toutes les FAQ<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b32e0fe\" data-id=\"1b32e0fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73f6accc elementor-widget elementor-widget-tp-accordion\" data-id=\"73f6accc\" data-element_type=\"widget\" data-widget_type=\"tp-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"theplus-accordion-wrapper elementor-accordion\" id=\"accordion6a04959bee2c3\" data-accordion-id=\"accordion6a04959bee2c3\" data-connection=\"\" data-accordion-type=\"accordion\" data-heightlight-text role=\"tablist\" > \r\n\t\t\r\n\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-1941\" class=\"elementor-tab-title plus-accordion-header 0 text-left\" data-tab=\"1\" aria-controls=\"elementor-tab-content-1941\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<span style=\"width:100%\">Quelle est la diff\u00e9rence entre le spectre complet et le spectre large ?<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-1941\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1941\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>Lorsqu'un extrait de CBD \u00e0 spectre complet est hivernis\u00e9 et purifi\u00e9, une partie du THC est \u00e9limin\u00e9e et une partie des cannabino\u00efdes acides est d\u00e9carboxyl\u00e9e. Il conserve encore beaucoup de cannabino\u00efdes et de terp\u00e8nes, mais il ne s'agit pas techniquement d'un extrait \u00e0 spectre complet. Nous appelons cela un extrait \u00e0 large spectre.<\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-1942\" class=\"elementor-tab-title plus-accordion-header 0 text-left\" data-tab=\"2\" aria-controls=\"elementor-tab-content-1942\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<span style=\"width:100%\">Quel type de gommes au CBD vendez-vous ?<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-1942\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1942\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>Nous proposons des gommes \u00e0 la g\u00e9latine traditionnelle et des gommes v\u00e9g\u00e9taliennes \u00e0 diff\u00e9rentes concentrations de CBD. Nous sommes heureux de vous envoyer un \u00e9chantillon pour que vous puissiez les go\u00fbter et en v\u00e9rifier la qualit\u00e9 avant de passer commande.<\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-1943\" class=\"elementor-tab-title plus-accordion-header 0 text-left\" data-tab=\"3\" aria-controls=\"elementor-tab-content-1943\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<span style=\"width:100%\">Peut-on ajouter des vitamines, des min\u00e9raux ou des suppl\u00e9ments \u00e0 base de plantes aux gommes ?<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-1943\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1943\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>Pour les commandes sup\u00e9rieures \u00e0 5 000 unit\u00e9s, nous pouvons d\u00e9velopper des gommes avec tous les additifs que vous souhaitez. Veuillez noter que cela peut entra\u00eener des co\u00fbts de d\u00e9veloppement du produit afin de s'assurer que votre additif se m\u00e9lange bien et qu'il est stable. <\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-1944\" class=\"elementor-tab-title plus-accordion-header 0 text-left\" data-tab=\"4\" aria-controls=\"elementor-tab-content-1944\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<span style=\"width:100%\">Quelle est la diff\u00e9rence entre la marque blanche et la marque priv\u00e9e ?<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-1944\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1944\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>La marque blanche consiste \u00e0 utiliser l'un de nos produits pr\u00e9existants et test\u00e9s. Nous fournissons les mod\u00e8les d'\u00e9tiquettes et d'emballages et vous vous chargez de la conception. Vous recevrez un produit fini portant votre logo et votre marque. Cela vous permet d'acc\u00e9der rapidement au march\u00e9 avec un investissement minimal.<\/p><p>La marque de distributeur vous permet d'\u00eatre plus cr\u00e9atif. Vous pouvez opter pour un m\u00e9lange personnalis\u00e9, formul\u00e9 uniquement pour vous, avec d'autres ingr\u00e9dients ou ar\u00f4mes ajout\u00e9s. La marque priv\u00e9e peut \u00e9galement vous donner plus de flexibilit\u00e9 en ce qui concerne la conception de l'\u00e9tiquette et de l'emballage ext\u00e9rieur. Pour les marques de distributeur, vous pouvez utiliser diff\u00e9rents r\u00e9cipients et bouteilles, et avoir un emballage ext\u00e9rieur personnalis\u00e9 avec divers embellissements imprim\u00e9s.<\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t<div class=\"theplus-accordion-item\"  role=\"tab\">\r\n\t\t\t\t\t<div id=\"elementor-tab-title-1945\" class=\"elementor-tab-title plus-accordion-header 0 text-left\" data-tab=\"5\" aria-controls=\"elementor-tab-content-1945\"\t\t\t\t\t>\r\n\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<span style=\"width:100%\">Quelles sont les certifications ISO\/GMP que vous d\u00e9tenez ?<\/span>\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div \r\n\t\t\t\t\t\tid=\"elementor-tab-content-1945\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1945\"\t\t\t\t\t\t> \r\n\t\t\t\t\t\t\t\t\t\t<div class=\"plus-content-editor\" ><p>CBD Oil Europe travaille avec diff\u00e9rents r\u00e9gimes de qualit\u00e9.<\/p><p>Notre programme cosm\u00e9tique est produit selon la norme 22716-2007 GMP (bonnes pratiques de fabrication).<\/p><p>Notre programme d'huile conventionnelle de CBD est produit selon les BPF (bonnes pratiques de fabrication) cosm\u00e9tiques ISO 22716-2007 et embouteill\u00e9 selon les r\u00e9gimes ISO 9001:2015 et ISO 22000:2005.<\/p><p>Nos isolats de CBD, nos distillats et nos produits solubles dans l'eau sont fabriqu\u00e9s selon les normes ISO 9000 et GMP.<\/p><p>Tout \u00e9chantillonnage ou reconditionnement au bureau est effectu\u00e9 dans une salle blanche modulaire ISO-5 (derni\u00e8re validation le 16-7-2020).<\/p><p>Vous pouvez consulter nos certifications de qualit\u00e9 <a href=\"https:\/\/cbdoileurope.com\/fr\/a-propos-de\/qualite-et-conformite\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">ici<\/span><\/a>.<\/p><\/div>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> \r\n\t\t\t\t\r\n\t\t<\/div>  \r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22689770 elementor-align-left elementor-tablet-align-center elementor-widget-tablet__width-inherit elementor-hidden-desktop elementor-widget elementor-widget-button\" data-id=\"22689770\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/cbdoileurope.com\/fr\/docs\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir toutes les FAQ<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27f28eb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"27f28eb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c532a0e\" data-id=\"c532a0e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65fe7f0 elementor-widget elementor-widget-template\" data-id=\"65fe7f0\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"394\" class=\"elementor elementor-394\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd2c56b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd2c56b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d6ce99\" data-id=\"7d6ce99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2511de5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2511de5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0c0064b\" data-id=\"0c0064b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-556672eb elementor-widget elementor-widget-heading\" data-id=\"556672eb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parlons CBD !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-905c90b elementor-widget elementor-widget-text-editor\" data-id=\"905c90b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prenez contact avec l'un de nos experts pour discuter de vos besoins. Nous vous aiderons tout au long du processus, de l'approvisionnement \u00e0 la distribution finale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6250ea5 elementor-tablet-align-justify elementor-widget-tablet__width-inherit elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"6250ea5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cbdoileurope.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9server une r\u00e9union<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bfaff6 elementor-tablet-align-justify elementor-widget-tablet__width-inherit elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"9bfaff6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cbdoileurope.com\/fr\/la-tarification\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demander une liste de prix<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-671f6d3\" data-id=\"671f6d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62808b9 elementor-widget elementor-widget-image\" data-id=\"62808b9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2.jpg\" class=\"attachment-large size-large wp-image-18112\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2.jpg 800w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-300x300.jpg 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-150x150.jpg 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-768x768.jpg 768w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-12x12.jpg 12w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-700x700.jpg 700w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-360x360.jpg 360w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-600x600.jpg 600w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Unique formula Full custom service Custom Gummies Customise the ingredients, shape, colour, and flavour of your gummies. Gummies are the perfect vehicle for taking active ingredients. Gummies are easy to take and people associate them with joy and happy moments. How can I develop a custom gummy? Development costs for a unique gummy are \u20ac800 [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":1306,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-6124","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.2 (Yoast SEO v23.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Custom CBD Gummies | Tailored Formulations | CBD Oil Europe<\/title>\n<meta name=\"description\" content=\"Create your own CBD gummy line with our custom formulation service. Choose flavors, shapes, and CBD content to match your brand&#039;s unique vision.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbdoileurope.com\/fr\/produits-cbd\/gommes-de-cbd\/gommes-personnalisees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Custom gummies\" \/>\n<meta property=\"og:description\" content=\"CBD Oil Europe specialises in white &amp; private label CBD. Wholesale CBD Oil, gummies, cosmetics, pet products, water soluble and distillate and isolate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbdoileurope.com\/fr\/produits-cbd\/gommes-de-cbd\/gommes-personnalisees\/\" \/>\n<meta property=\"og:site_name\" content=\"CBD Oil Europe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-1024x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/\",\"url\":\"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/\",\"name\":\"Custom CBD Gummies | Tailored Formulations | CBD Oil Europe\",\"isPartOf\":{\"@id\":\"https:\/\/cbdoileurope.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-1024x1024.jpg\",\"datePublished\":\"2024-03-14T14:24:55+00:00\",\"dateModified\":\"2024-03-14T14:24:55+00:00\",\"description\":\"Create your own CBD gummy line with our custom formulation service. Choose flavors, shapes, and CBD content to match your brand's unique vision.\",\"breadcrumb\":{\"@id\":\"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/#primaryimage\",\"url\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-1024x1024.jpg\",\"contentUrl\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-1024x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cbdoileurope.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/cbdoileurope.com\/products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CBD Gummies\",\"item\":\"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Custom gummies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cbdoileurope.com\/#website\",\"url\":\"https:\/\/cbdoileurope.com\/\",\"name\":\"CBD Oil Europe\",\"description\":\"Simplifying CBD\",\"publisher\":{\"@id\":\"https:\/\/cbdoileurope.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cbdoileurope.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cbdoileurope.com\/#organization\",\"name\":\"CBD Oil Europe\",\"url\":\"https:\/\/cbdoileurope.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg\",\"contentUrl\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg\",\"width\":432,\"height\":169,\"caption\":\"CBD Oil Europe\"},\"image\":{\"@id\":\"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/78547167\/\"],\"description\":\"CBD Oil Europe specialises in white label, private label and wholesale CBD products & services. Our product offering includes oil blends, gummies, capsules, cosmetics, pet products, water solubles and CBD extracts such as distillate and isolate. All of our research & development, packaging, label design and fulfilment services are done in-house by the members of our passionate and competent team. Founder and director Adriaan de Kroo started at the bottom of the non-existing CBD industry in 2013, helping other startups with sales and consultancy around this relatively new compound. He represented several of the biggest CBD producers and traders at more than 35 trade shows, from Sevilla to Moscow.\",\"email\":\"info@cbdoileurope.com\",\"telephone\":\"+31640690002\",\"legalName\":\"CBD Oil Europe\",\"foundingDate\":\"2013-06-02\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Custom CBD Gummies | Tailored Formulations | CBD Oil Europe","description":"Create your own CBD gummy line with our custom formulation service. Choose flavors, shapes, and CBD content to match your brand's unique vision.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbdoileurope.com\/fr\/produits-cbd\/gommes-de-cbd\/gommes-personnalisees\/","og_locale":"fr_FR","og_type":"article","og_title":"Custom gummies","og_description":"CBD Oil Europe specialises in white & private label CBD. Wholesale CBD Oil, gummies, cosmetics, pet products, water soluble and distillate and isolate.","og_url":"https:\/\/cbdoileurope.com\/fr\/produits-cbd\/gommes-de-cbd\/gommes-personnalisees\/","og_site_name":"CBD Oil Europe","og_image":[{"url":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-1024x1024.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/","url":"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/","name":"Custom CBD Gummies | Tailored Formulations | CBD Oil Europe","isPartOf":{"@id":"https:\/\/cbdoileurope.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/#primaryimage"},"image":{"@id":"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/#primaryimage"},"thumbnailUrl":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-1024x1024.jpg","datePublished":"2024-03-14T14:24:55+00:00","dateModified":"2024-03-14T14:24:55+00:00","description":"Create your own CBD gummy line with our custom formulation service. Choose flavors, shapes, and CBD content to match your brand's unique vision.","breadcrumb":{"@id":"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/#primaryimage","url":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-1024x1024.jpg","contentUrl":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4723_60gummies_jar_white_cap-1024x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/custom-gummies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbdoileurope.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/cbdoileurope.com\/products\/"},{"@type":"ListItem","position":3,"name":"CBD Gummies","item":"https:\/\/cbdoileurope.com\/products\/cbd-gummies\/"},{"@type":"ListItem","position":4,"name":"Custom gummies"}]},{"@type":"WebSite","@id":"https:\/\/cbdoileurope.com\/#website","url":"https:\/\/cbdoileurope.com\/","name":"CBD Oil Europe","description":"Simplifying CBD","publisher":{"@id":"https:\/\/cbdoileurope.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbdoileurope.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cbdoileurope.com\/#organization","name":"CBD Oil Europe","url":"https:\/\/cbdoileurope.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/","url":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg","contentUrl":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg","width":432,"height":169,"caption":"CBD Oil Europe"},"image":{"@id":"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/78547167\/"],"description":"CBD Oil Europe specialises in white label, private label and wholesale CBD products & services. Our product offering includes oil blends, gummies, capsules, cosmetics, pet products, water solubles and CBD extracts such as distillate and isolate. All of our research & development, packaging, label design and fulfilment services are done in-house by the members of our passionate and competent team. Founder and director Adriaan de Kroo started at the bottom of the non-existing CBD industry in 2013, helping other startups with sales and consultancy around this relatively new compound. He represented several of the biggest CBD producers and traders at more than 35 trade shows, from Sevilla to Moscow.","email":"info@cbdoileurope.com","telephone":"+31640690002","legalName":"CBD Oil Europe","foundingDate":"2013-06-02"}]}},"_links":{"self":[{"href":"https:\/\/cbdoileurope.com\/fr\/wp-json\/wp\/v2\/pages\/6124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbdoileurope.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cbdoileurope.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cbdoileurope.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbdoileurope.com\/fr\/wp-json\/wp\/v2\/comments?post=6124"}],"version-history":[{"count":118,"href":"https:\/\/cbdoileurope.com\/fr\/wp-json\/wp\/v2\/pages\/6124\/revisions"}],"predecessor-version":[{"id":18229,"href":"https:\/\/cbdoileurope.com\/fr\/wp-json\/wp\/v2\/pages\/6124\/revisions\/18229"}],"up":[{"embeddable":true,"href":"https:\/\/cbdoileurope.com\/fr\/wp-json\/wp\/v2\/pages\/1306"}],"wp:attachment":[{"href":"https:\/\/cbdoileurope.com\/fr\/wp-json\/wp\/v2\/media?parent=6124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}