{"id":16887,"date":"2024-03-14T14:25:12","date_gmt":"2024-03-14T14:25:12","guid":{"rendered":"https:\/\/cbdoileurope.com\/?page_id=16887"},"modified":"2024-08-22T12:56:55","modified_gmt":"2024-08-22T12:56:55","slug":"contract-manufacturing","status":"publish","type":"page","link":"https:\/\/cbdoileurope.com\/es\/servicios-de-cbd\/fabricacion-por-encargo\/","title":{"rendered":"Fabricaci\u00f3n por contrato"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"16887\" class=\"elementor elementor-16887\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca3d785 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ca3d785\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;curve&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,97C126.7,96.3,0.8,19.8,0,0v100l1000,0V1C1000,19.4,873.3,97.8,500,97z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a476c4d\" data-id=\"5a476c4d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3cca8799 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cca8799\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4ea597d7\" data-id=\"4ea597d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27d1d967 elementor-widget elementor-widget-woocommerce-breadcrumb\" data-id=\"27d1d967\" data-element_type=\"widget\" data-widget_type=\"woocommerce-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"woocommerce-breadcrumb\" data-no-translation=\"\" data-trp-gettext=\"\">Inicio<\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7f646a69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f646a69\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-13e549b\" data-id=\"13e549b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6710a157 elementor-widget elementor-widget-heading\" data-id=\"6710a157\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fabricaci\u00f3n por contrato<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e585699 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e585699\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d2bc48\" data-id=\"2d2bc48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d09e4a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d09e4a3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-458ed77\" data-id=\"458ed77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccbcbfb elementor-widget elementor-widget-heading\" data-id=\"ccbcbfb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Fabricaci\u00f3n por contrato<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb14785 elementor-widget elementor-widget-heading\" data-id=\"bb14785\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tenemos m\u00e1s de 20 a\u00f1os de experiencia en la producci\u00f3n de marcas blancas para cadenas minoristas.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2e7f2f elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d2e7f2f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Desarrollo de productos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Servicios anal\u00edticos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Apoyo en cuestiones reglamentarias<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mezcla de materias primas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fabricaci\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Embalaje<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-211c787\" data-id=\"211c787\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cb3b4e elementor-widget elementor-widget-text-editor\" data-id=\"4cb3b4e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gracias a nuestra experiencia en la producci\u00f3n de gominolas a alta velocidad, el embotellado de aceites y bebidas de CBD, la purificaci\u00f3n del agua y la encapsulaci\u00f3n de polvos, podemos satisfacer una amplia gama de necesidades de fabricaci\u00f3n.\u00a0<span style=\"background-color: var( --e-global-color-1b23c16 ); font-size: 19.2px;\">P\u00f3ngase en contacto con nosotros para sus necesidades de fabricaci\u00f3n de marcas blancas y privadas.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2239b88 elementor-widget elementor-widget-heading\" data-id=\"2239b88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Desarrollo de productos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e43bdd elementor-widget elementor-widget-text-editor\" data-id=\"8e43bdd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tras haber gestionado cientos de proyectos de desarrollo de marcas blancas, somos expertos en sacar ideas al mercado con rapidez y dentro del marco normativo correcto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5830bcf elementor-widget elementor-widget-button\" data-id=\"5830bcf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cbdoileurope.com\/es\/servicios-de-cbd\/marca-blanca\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Seguir leyendo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2941b54c elementor-widget elementor-widget-heading\" data-id=\"2941b54c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Normas de calidad<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f7e3ba3 elementor-widget elementor-widget-gallery\" data-id=\"4f7e3ba3\" data-element_type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;justified&quot;,&quot;ideal_row_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:90,&quot;sizes&quot;:[]},&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;ideal_row_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:90,&quot;sizes&quot;:[]},&quot;ideal_row_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:80,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]}}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-GMP-v1-1-150x150.webp\" data-width=\"150\" data-height=\"150\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-HACCP-v1-1-150x150.webp\" data-width=\"150\" data-height=\"150\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1-150x150.webp\" data-width=\"150\" data-height=\"150\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EU-v1-1-150x150.webp\" data-width=\"150\" data-height=\"150\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ba3585c elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"5ba3585c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/cbdoileurope.com\/es\/acerca-de\/calidad-y-conformidad\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Seguir leyendo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-668debb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"668debb8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2dd3ddf7\" data-id=\"2dd3ddf7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77a06712 elementor-widget elementor-widget-gallery\" data-id=\"77a06712\" data-element_type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns_tablet&quot;:3,&quot;columns_mobile&quot;:2,&quot;columns&quot;:3,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-06-1024x480.jpg\" data-width=\"800\" data-height=\"375\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-03-1024x768.jpg\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/11\/CBD-Services-ContractManufacturing-17-1024x576.jpg\" data-width=\"800\" data-height=\"450\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-01-1024x768.jpg\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/11\/CBD-Services-ContractManufacturing-02-3-1024x767.jpg\" data-width=\"800\" data-height=\"599\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/07\/CBDEU-CBD-Products-Terpenes-v2-1-1024x576.jpg\" data-width=\"800\" data-height=\"450\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-05-1024x768.jpg\" data-width=\"800\" data-height=\"600\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-04-1024x512.jpg\" data-width=\"800\" data-height=\"400\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/11\/CBD-Services-ContractManufacturing-18-1024x683.jpg\" data-width=\"800\" data-height=\"534\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1db8da25 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"1db8da25\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=yi0_VDqHCAg&quot;,&quot;background_video_start&quot;:9,&quot;background_video_end&quot;:0,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69abac48\" data-id=\"69abac48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22ba241c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"22ba241c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bf0f55f\" data-id=\"3bf0f55f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e35c681 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e35c681\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-5d55d48\" data-id=\"5d55d48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab78694 elementor-widget elementor-widget-heading\" data-id=\"ab78694\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Aceites<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ead1330 elementor-widget elementor-widget-text-editor\" data-id=\"ead1330\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Embotellado de aceites de CBD 2.500 pcs\/h de botellas de vidrio de 10mL con pipetas.<\/li><li>Botellas de 2,5mL a 1.000mL.<\/li><li>Disponemos siempre de botellas est\u00e1ndar de 10 ml y 30 ml.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-edeae0e\" data-id=\"edeae0e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-911f541 elementor--v-position-bottom elementor--h-position-center elementor-arrows-position-inside elementor-widget elementor-widget-slides\" data-id=\"911f541\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay_speed&quot;:4000,&quot;transition&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-9a4e6ad swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-7f3e1e7 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva siguiente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0b8aff0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b8aff0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7d6b68e\" data-id=\"7d6b68e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad30ffb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ad30ffb\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b7aeff0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b7aeff0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53d4035\" data-id=\"53d4035\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46319072 elementor-widget elementor-widget-image\" data-id=\"46319072\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-1024x1024.jpg\" class=\"attachment-large size-large wp-image-6430\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-1024x1024.jpg 1024w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-300x300.jpg 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-150x150.jpg 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-768x768.jpg 768w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-1536x1536.jpg 1536w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-2048x2048.jpg 2048w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-700x700.jpg 700w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-600x600.jpg 600w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-571f37fd\" data-id=\"571f37fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75cf664b elementor-widget elementor-widget-heading\" data-id=\"75cf664b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Gominolas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24308ee3 elementor-widget elementor-widget-text-editor\" data-id=\"24308ee3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Producci\u00f3n de gominolas de gelatina y pectina<\/li>\n<li>Gominolas - 50.000 unidades por hora<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-23745305 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23745305\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-44649c02\" data-id=\"44649c02\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-637eb184 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"637eb184\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8e2068e elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e2068e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-0c26ee2\" data-id=\"0c26ee2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd82587 elementor-widget elementor-widget-heading\" data-id=\"bd82587\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bebidas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7beca8 elementor-widget elementor-widget-text-editor\" data-id=\"f7beca8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Producci\u00f3n y depuraci\u00f3n de agua 20.000L\/h,<\/li><li>Producci\u00f3n de agua destilada ~10\u00b5S - 6.000L\/h <\/li><li>Embotellado de agua, zumos, jarabes y bebidas gaseosas 6.000L\/h Botellas de 0,33-2L <\/li><li>Embotellado de agua, jarabes de botellas de 3-10L <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d479613\" data-id=\"d479613\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afe97d1 elementor--v-position-bottom elementor--h-position-center elementor-arrows-position-inside elementor-widget elementor-widget-slides\" data-id=\"afe97d1\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay_speed&quot;:4000,&quot;transition&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-9a4e6ad swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-68976f0 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva siguiente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d1f4983 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1f4983\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ed470eb\" data-id=\"ed470eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b38dc4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1b38dc4\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-afad6bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"afad6bc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-891b6ae\" data-id=\"891b6ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e4ac49 elementor-widget elementor-widget-image\" data-id=\"6e4ac49\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-07-2.jpg\" class=\"attachment-large size-large wp-image-16952\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-07-2.jpg 800w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-07-2-300x300.jpg 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-07-2-150x150.jpg 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-07-2-768x768.jpg 768w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-07-2-700x700.jpg 700w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-07-2-360x360.jpg 360w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-07-2-600x600.jpg 600w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-07-2-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-180e6bf\" data-id=\"180e6bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f10cab0 elementor-widget elementor-widget-heading\" data-id=\"f10cab0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Aceites prensados en fr\u00edo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61cfbb1 elementor-widget elementor-widget-text-editor\" data-id=\"61cfbb1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Producci\u00f3n de aceite Prensado en fr\u00edo de granos de aceite - Embotellado de aceites en botellas de vidrio de 0,25 - 1L<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-35ca7c3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35ca7c3b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5f300f15\" data-id=\"5f300f15\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28be9cf2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"28be9cf2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-50b51e6a elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50b51e6a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-8fd1302\" data-id=\"8fd1302\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e315011 elementor-widget elementor-widget-heading\" data-id=\"e315011\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cosm\u00e9ticos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba44b15 elementor-widget elementor-widget-text-editor\" data-id=\"ba44b15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Homogeneizaci\u00f3n de aceites de CBD y otros cosm\u00e9ticos\u00a0<\/li><li>Llenado de cremas en tarros o tubos sin aire\u00a0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-736e31b1\" data-id=\"736e31b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40320ac elementor--v-position-bottom elementor--h-position-center elementor-arrows-position-inside elementor-widget elementor-widget-slides\" data-id=\"40320ac\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay_speed&quot;:4000,&quot;transition&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-eb8540e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-9a4e6ad swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-68976f0 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva siguiente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-32b6ae2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32b6ae2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dc95f75\" data-id=\"dc95f75\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e944ac elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8e944ac\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2964fc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2964fc1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-38b2ab9\" data-id=\"38b2ab9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bcb2e7 elementor-widget elementor-widget-image\" data-id=\"2bcb2e7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-16-1024x1024.jpg\" class=\"attachment-large size-large wp-image-16961\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-16-1024x1024.jpg 1024w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-16-300x300.jpg 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-16-150x150.jpg 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-16-768x768.jpg 768w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-16-700x700.jpg 700w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-16-360x360.jpg 360w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-16-600x600.jpg 600w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-16-100x100.jpg 100w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/10\/CBD-Services-ContractManufacturing-16.jpg 1440w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-e3ed2de\" data-id=\"e3ed2de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-415e3d1 elementor-widget elementor-widget-heading\" data-id=\"415e3d1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Confiter\u00eda<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6792d38 elementor-widget elementor-widget-text-editor\" data-id=\"6792d38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Producci\u00f3n de galletas y brownies<\/li><li><span style=\"font-weight: 400;\">Productos de confiter\u00eda con ingredientes funcionales como la seta Melena de Le\u00f3n<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-291f3d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"291f3d7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8cdbd96\" data-id=\"8cdbd96\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ece5809 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ece5809\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d833154 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d833154\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-58d974f\" data-id=\"58d974f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1710513a elementor-widget elementor-widget-heading\" data-id=\"1710513a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">C\u00e1psulas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f9688d0 elementor-widget elementor-widget-text-editor\" data-id=\"3f9688d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Encapsulaci\u00f3n de polvos y comprimidos<\/li><li><span style=\"font-weight: 400;\">C\u00e1psulas rellenas de aceite en ampollas y tarros<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8d3e19a\" data-id=\"8d3e19a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-604c8ae elementor--v-position-bottom elementor--h-position-center elementor-arrows-position-inside elementor-widget elementor-widget-slides\" data-id=\"604c8ae\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay_speed&quot;:4000,&quot;transition&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-9a4e6ad swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-1743dcc swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-68976f0 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-b4b11de swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-eb8540e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositiva siguiente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa07b86 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"aa07b86\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-147523d\" data-id=\"147523d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2aee212 elementor-widget elementor-widget-template\" data-id=\"2aee212\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"394\" class=\"elementor elementor-394\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd2c56b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd2c56b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d6ce99\" data-id=\"7d6ce99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2511de5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2511de5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0c0064b\" data-id=\"0c0064b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-556672eb elementor-widget elementor-widget-heading\" data-id=\"556672eb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hablemos de CBD<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-905c90b elementor-widget elementor-widget-text-editor\" data-id=\"905c90b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>P\u00f3ngase en contacto con uno de nuestros expertos para hablar de sus necesidades. Le ayudaremos en todo el proceso, desde el aprovisionamiento hasta la distribuci\u00f3n final.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6250ea5 elementor-tablet-align-justify elementor-widget-tablet__width-inherit elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"6250ea5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cbdoileurope.com\/es\/pongase-en-contacto-con\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Concierte una reuni\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bfaff6 elementor-tablet-align-justify elementor-widget-tablet__width-inherit elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"9bfaff6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cbdoileurope.com\/es\/precios\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar lista de precios<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-671f6d3\" data-id=\"671f6d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62808b9 elementor-widget elementor-widget-image\" data-id=\"62808b9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2.jpg\" class=\"attachment-large size-large wp-image-18112\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2.jpg 800w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-300x300.jpg 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-150x150.jpg 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-768x768.jpg 768w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-12x12.jpg 12w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-700x700.jpg 700w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-360x360.jpg 360w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-600x600.jpg 600w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-CBD-Company-Team-Paul-v2-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Fabricaci\u00f3n por contrato Fabricaci\u00f3n por contrato Contamos con m\u00e1s de 20 a\u00f1os de experiencia en la producci\u00f3n de marcas blancas para cadenas minoristas. Desarrollo de productos Servicios anal\u00edticos Apoyo en cuestiones normativas Mezcla de materias primas Fabricaci\u00f3n Envasado Con experiencia en la producci\u00f3n de gominolas a alta velocidad, el embotellado de aceites y bebidas de CBD, la purificaci\u00f3n del agua y la encapsulaci\u00f3n de polvos, tenemos la capacidad de manejar una [...]<\/p>","protected":false},"author":1,"featured_media":0,"parent":443,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-16887","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.2 (Yoast SEO v23.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contract Manufacturing - CBD Oil Europe<\/title>\n<meta name=\"description\" content=\"we have the ability to handle a diverse range of manufacturing needs. Contact us for your white and private label manufacturing needs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbdoileurope.com\/es\/servicios-de-cbd\/fabricacion-por-encargo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contract Manufacturing\" \/>\n<meta property=\"og:description\" content=\"CBD Oil Europe specialises in white &amp; private label CBD. Wholesale CBD Oil, gummies, cosmetics, pet products, water soluble and distillate and isolate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbdoileurope.com\/es\/servicios-de-cbd\/fabricacion-por-encargo\/\" \/>\n<meta property=\"og:site_name\" content=\"CBD Oil Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-22T12:56:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-1024x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/\",\"url\":\"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/\",\"name\":\"Contract Manufacturing - CBD Oil Europe\",\"isPartOf\":{\"@id\":\"https:\/\/cbdoileurope.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-1024x1024.jpg\",\"datePublished\":\"2024-03-14T14:25:12+00:00\",\"dateModified\":\"2024-08-22T12:56:55+00:00\",\"description\":\"we have the ability to handle a diverse range of manufacturing needs. Contact us for your white and private label manufacturing needs.\",\"breadcrumb\":{\"@id\":\"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/#primaryimage\",\"url\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-1024x1024.jpg\",\"contentUrl\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-1024x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cbdoileurope.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CBD Services\",\"item\":\"https:\/\/cbdoileurope.com\/cbd-services\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Contract Manufacturing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cbdoileurope.com\/#website\",\"url\":\"https:\/\/cbdoileurope.com\/\",\"name\":\"CBD Oil Europe\",\"description\":\"Simplifying CBD\",\"publisher\":{\"@id\":\"https:\/\/cbdoileurope.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cbdoileurope.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cbdoileurope.com\/#organization\",\"name\":\"CBD Oil Europe\",\"url\":\"https:\/\/cbdoileurope.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg\",\"contentUrl\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg\",\"width\":432,\"height\":169,\"caption\":\"CBD Oil Europe\"},\"image\":{\"@id\":\"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/78547167\/\"],\"description\":\"CBD Oil Europe specialises in white label, private label and wholesale CBD products & services. Our product offering includes oil blends, gummies, capsules, cosmetics, pet products, water solubles and CBD extracts such as distillate and isolate. All of our research & development, packaging, label design and fulfilment services are done in-house by the members of our passionate and competent team. Founder and director Adriaan de Kroo started at the bottom of the non-existing CBD industry in 2013, helping other startups with sales and consultancy around this relatively new compound. He represented several of the biggest CBD producers and traders at more than 35 trade shows, from Sevilla to Moscow.\",\"email\":\"info@cbdoileurope.com\",\"telephone\":\"+31640690002\",\"legalName\":\"CBD Oil Europe\",\"foundingDate\":\"2013-06-02\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Contract Manufacturing - CBD Oil Europe","description":"we have the ability to handle a diverse range of manufacturing needs. Contact us for your white and private label manufacturing needs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbdoileurope.com\/es\/servicios-de-cbd\/fabricacion-por-encargo\/","og_locale":"es_ES","og_type":"article","og_title":"Contract Manufacturing","og_description":"CBD Oil Europe specialises in white & private label CBD. Wholesale CBD Oil, gummies, cosmetics, pet products, water soluble and distillate and isolate.","og_url":"https:\/\/cbdoileurope.com\/es\/servicios-de-cbd\/fabricacion-por-encargo\/","og_site_name":"CBD Oil Europe","article_modified_time":"2024-08-22T12:56:55+00:00","og_image":[{"url":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-1024x1024.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/","url":"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/","name":"Contract Manufacturing - CBD Oil Europe","isPartOf":{"@id":"https:\/\/cbdoileurope.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/#primaryimage"},"image":{"@id":"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/#primaryimage"},"thumbnailUrl":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-1024x1024.jpg","datePublished":"2024-03-14T14:25:12+00:00","dateModified":"2024-08-22T12:56:55+00:00","description":"we have the ability to handle a diverse range of manufacturing needs. Contact us for your white and private label manufacturing needs.","breadcrumb":{"@id":"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/#primaryimage","url":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-1024x1024.jpg","contentUrl":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/04\/IMG_4769_fruit_mix_gummies-1024x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cbdoileurope.com\/cbd-services\/contract-manufacturing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbdoileurope.com\/"},{"@type":"ListItem","position":2,"name":"CBD Services","item":"https:\/\/cbdoileurope.com\/cbd-services\/"},{"@type":"ListItem","position":3,"name":"Contract Manufacturing"}]},{"@type":"WebSite","@id":"https:\/\/cbdoileurope.com\/#website","url":"https:\/\/cbdoileurope.com\/","name":"CBD Oil Europe","description":"Simplifying CBD","publisher":{"@id":"https:\/\/cbdoileurope.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbdoileurope.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cbdoileurope.com\/#organization","name":"CBD Oil Europe","url":"https:\/\/cbdoileurope.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/","url":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg","contentUrl":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg","width":432,"height":169,"caption":"CBD Oil Europe"},"image":{"@id":"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/78547167\/"],"description":"CBD Oil Europe specialises in white label, private label and wholesale CBD products & services. Our product offering includes oil blends, gummies, capsules, cosmetics, pet products, water solubles and CBD extracts such as distillate and isolate. All of our research & development, packaging, label design and fulfilment services are done in-house by the members of our passionate and competent team. Founder and director Adriaan de Kroo started at the bottom of the non-existing CBD industry in 2013, helping other startups with sales and consultancy around this relatively new compound. He represented several of the biggest CBD producers and traders at more than 35 trade shows, from Sevilla to Moscow.","email":"info@cbdoileurope.com","telephone":"+31640690002","legalName":"CBD Oil Europe","foundingDate":"2013-06-02"}]}},"_links":{"self":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/pages\/16887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/comments?post=16887"}],"version-history":[{"count":69,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/pages\/16887\/revisions"}],"predecessor-version":[{"id":18307,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/pages\/16887\/revisions\/18307"}],"up":[{"embeddable":true,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/pages\/443"}],"wp:attachment":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/media?parent=16887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}