{"id":1504,"date":"2024-03-14T14:24:17","date_gmt":"2024-03-14T14:24:17","guid":{"rendered":"https:\/\/cbdoileurope.com\/?page_id=1504"},"modified":"2024-08-22T12:43:44","modified_gmt":"2024-08-22T12:43:44","slug":"quality-and-compliance","status":"publish","type":"page","link":"https:\/\/cbdoileurope.com\/es\/acerca-de\/calidad-y-conformidad\/","title":{"rendered":"Calidad y conformidad"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1504\" class=\"elementor elementor-1504\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca3d785 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ca3d785\" data-element_type=\"section\" id=\"qualitycompliancetop\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;curve&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,97C126.7,96.3,0.8,19.8,0,0v100l1000,0V1C1000,19.4,873.3,97.8,500,97z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a476c4d\" data-id=\"5a476c4d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3cca8799 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cca8799\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4ea597d7\" data-id=\"4ea597d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27d1d967 elementor-widget elementor-widget-woocommerce-breadcrumb\" data-id=\"27d1d967\" data-element_type=\"widget\" data-widget_type=\"woocommerce-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"woocommerce-breadcrumb\" data-no-translation=\"\" data-trp-gettext=\"\">Inicio<\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7f646a69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f646a69\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-13e549b\" data-id=\"13e549b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6710a157 elementor-widget elementor-widget-heading\" data-id=\"6710a157\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Calidad y conformidad<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e585699 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e585699\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d2bc48\" data-id=\"2d2bc48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d09e4a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d09e4a3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-458ed77\" data-id=\"458ed77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccbcbfb elementor-widget elementor-widget-heading\" data-id=\"ccbcbfb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Gesti\u00f3n de la calidad<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e6d80b elementor-widget elementor-widget-heading\" data-id=\"1e6d80b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Altos niveles de calidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-211c787\" data-id=\"211c787\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b3d1e0 elementor-widget elementor-widget-heading\" data-id=\"7b3d1e0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Navega r\u00e1pidamente hasta:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b5040e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1b5040e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#gmpisohaccp\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">GMP, ISO, HACCP<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#labtesting\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pruebas de laboratorio propias y de terceros<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#qualitydocumentation\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Documentaci\u00f3n de calidad<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#cosmetics\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">CPNP &amp; CPSR Cosm\u00e9ticos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#organic\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Certificaci\u00f3n ecol\u00f3gica<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9147f55 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9147f55\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96ee7d5\" data-id=\"96ee7d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d27a39 elementor-widget elementor-widget-menu-anchor\" data-id=\"0d27a39\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"gmpisohaccp\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d79d3d4 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d79d3d4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6178f1f\" data-id=\"6178f1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cb0f3b elementor-widget elementor-widget-heading\" data-id=\"6cb0f3b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Certificaci\u00f3n de calidad<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-413b7a9 elementor-widget elementor-widget-heading\" data-id=\"413b7a9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">GMP, ISO, HACCP<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-414254d elementor-widget elementor-widget-text-editor\" data-id=\"414254d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestra planta de producci\u00f3n croata est\u00e1 certificada para <span style=\"text-decoration: underline;\"><a href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2023\/11\/CBD-Oil-Europe-CBDEU-Compliance-A4-ENG.pdf\" target=\"_blank\" rel=\"noopener\">BPF Codex Alimentarius, ISO 9001:2015 y APPCC<\/a><\/span> as\u00ed como cosm\u00e9ticos ISO 22716-2007. Nuestras instalaciones de producci\u00f3n se encuentran en los Pa\u00edses Bajos y Croacia. Nuestra sede central est\u00e1 en los Pa\u00edses Bajos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f448ad elementor-widget elementor-widget-button\" data-id=\"6f448ad\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#qualitycompliancetop\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-up\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver arriba<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2e2a300\" data-id=\"2e2a300\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa5fd97 elementor-widget elementor-widget-image\" data-id=\"fa5fd97\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1.webp\" class=\"attachment-large size-large wp-image-131\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1.webp 400w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1-300x300.webp 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1-150x150.webp 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1-100x100.webp 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3bf20d elementor-widget elementor-widget-menu-anchor\" data-id=\"f3bf20d\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"labtesting\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-92aeaf0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92aeaf0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11840cc\" data-id=\"11840cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aed8d89 elementor-widget elementor-widget-image\" data-id=\"aed8d89\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-GMP-v1-1.webp\" class=\"attachment-large size-large wp-image-133\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-GMP-v1-1.webp 400w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-GMP-v1-1-300x300.webp 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-GMP-v1-1-150x150.webp 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-GMP-v1-1-100x100.webp 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2ac28cc\" data-id=\"2ac28cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa55e9d elementor-widget elementor-widget-heading\" data-id=\"fa55e9d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Pruebas de laboratorio<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cebba1 elementor-widget elementor-widget-heading\" data-id=\"7cebba1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pruebas de laboratorio propias y de terceros<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-851f75a elementor-widget elementor-widget-text-editor\" data-id=\"851f75a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Disponemos de nuestro propio laboratorio de pruebas con equipos HPLC de \u00faltima generaci\u00f3n. Realizamos pruebas en todas las fases de producci\u00f3n.<\/p><p>Para las pruebas de laboratorio de terceros, nuestro principal proveedor es Eurofins. Ellos son\u00a0<a href=\"https:\/\/en.wikipedia.org\/wiki\/ISO\/IEC_17025\" target=\"_blank\" rel=\"noopener\"><u>Cumple la norma EN ISO\/IEC 17025<\/u><\/a>. Este es el principal <span style=\"text-decoration: underline;\"><a href=\"https:\/\/en.wikipedia.org\/wiki\/List_of_International_Organization_for_Standardization_standards\" target=\"_blank\" rel=\"noopener\">Norma ISO<\/a><\/span> utilizado internacionalmente por los laboratorios de ensayo y calibraci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4b5de6 elementor-widget elementor-widget-text-editor\" data-id=\"e4b5de6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Probamos nuestras materias primas para:<\/strong><\/p><ul><li>Metales pesados<\/li><li>Pesticidas<\/li><li>Micotoxinas<\/li><li>Contaminaci\u00f3n microbiana<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2addc0 elementor-widget elementor-widget-text-editor\" data-id=\"c2addc0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"color: var( --e-global-color-dbfa98e ); font-family: var( --e-global-typography-ebc58c5-font-family ), Sans-serif; font-size: var( --e-global-typography-ebc58c5-font-size ); letter-spacing: var( --e-global-typography-ebc58c5-letter-spacing ); word-spacing: var( --e-global-typography-ebc58c5-word-spacing ); background-color: var( --e-global-color-c1d1240 );\">Otras pruebas disponibles previa solicitud:<\/strong><\/p><ul><li>An\u00e1lisis de terpenos<\/li><li>An\u00e1lisis de laboratorio de los hechos relativos a los nutrientes<\/li><li>HAP's<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-648712a elementor-widget elementor-widget-button\" data-id=\"648712a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#qualitycompliancetop\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-up\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver arriba<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c4923d elementor-widget elementor-widget-menu-anchor\" data-id=\"0c4923d\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"qualitydocumentation\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0e5d66a elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e5d66a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-57864e9\" data-id=\"57864e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67ba48c elementor-widget elementor-widget-heading\" data-id=\"67ba48c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Cumplimiento legal<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b47335d elementor-widget elementor-widget-heading\" data-id=\"b47335d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Documentaci\u00f3n de calidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cacb3b elementor-widget elementor-widget-text-editor\" data-id=\"3cacb3b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Todos nuestros productos est\u00e1n cubiertos por nuestra amplia documentaci\u00f3n de calidad para garantizar el cumplimiento de la legislaci\u00f3n. De serie disponemos de:<\/p><ul><li>Especificaci\u00f3n del producto - TDS<\/li><li>Ficha de datos de seguridad - FDS<\/li><li>Certificado de an\u00e1lisis - COA<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d96905 elementor-widget elementor-widget-text-editor\" data-id=\"5d96905\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>Tambi\u00e9n podemos facilitarle cualquier otra documentaci\u00f3n jur\u00eddica o t\u00e9cnica que necesite.\u00a0<\/div><div>\u00a0<\/div><ul><li>Declaraci\u00f3n de conformidad - Certificado de conformidad con el Reglamento 1223\/2009 de la UE. Incluye: Al\u00e9rgenos, modificaci\u00f3n gen\u00e9tica, nanomateriales, radiactividad e ionizaci\u00f3n<\/li><li>Declaraci\u00f3n de origen de la UE<\/li><li>Declaraci\u00f3n de Cero THC<\/li><li>Declaraci\u00f3n de ventas en Europa<\/li><li>Declaraci\u00f3n de las partes de plantas utilizadas<\/li><li>Declaraci\u00f3n vegana<\/li><li>Declaraci\u00f3n de no experimentaci\u00f3n con animales<\/li><li>Diagrama del proceso de fabricaci\u00f3n<\/li><li>Tabla de valores nutricionales<\/li><li>Declaraci\u00f3n CMR Directiva sobre cosm\u00e9ticos de la UE 1272\/2008 (CE)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab11e41 elementor-widget elementor-widget-text-editor\" data-id=\"ab11e41\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tambi\u00e9n podemos suministrar un dossier cosm\u00e9tico completo para nuestros productos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe145d9 elementor-widget elementor-widget-button\" data-id=\"fe145d9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#qualitycompliancetop\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-up\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver arriba<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0c575d0\" data-id=\"0c575d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab232d8 elementor-widget elementor-widget-image\" data-id=\"ab232d8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-HACCP-v1-1.webp\" class=\"attachment-large size-large wp-image-132\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-HACCP-v1-1.webp 400w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-HACCP-v1-1-300x300.webp 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-HACCP-v1-1-150x150.webp 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-HACCP-v1-1-100x100.webp 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec7d071 elementor-widget elementor-widget-menu-anchor\" data-id=\"ec7d071\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"cosmetics\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cf61d6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf61d6d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6206776\" data-id=\"6206776\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5736de0 elementor-widget elementor-widget-image\" data-id=\"5736de0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EU-v1-1.webp\" class=\"attachment-large size-large wp-image-134\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EU-v1-1.webp 400w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EU-v1-1-300x300.webp 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EU-v1-1-150x150.webp 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EU-v1-1-100x100.webp 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7cda6cf\" data-id=\"7cda6cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7db6619 elementor-widget elementor-widget-heading\" data-id=\"7db6619\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dossier sobre cosm\u00e9ticos<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-497424a elementor-widget elementor-widget-heading\" data-id=\"497424a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CPNP &amp; CPSR Cosm\u00e9ticos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-175d2e4 elementor-widget elementor-widget-text-editor\" data-id=\"175d2e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestro programa de cosm\u00e9ticos le ofrece un completo expediente de cosm\u00e9ticos para que pueda registrar sus productos en el CPNP y venderlos legalmente en toda la UE.<\/p><p><strong>Inscripci\u00f3n en la CPNP<\/strong><br \/>Si tiene intenci\u00f3n de registrar los productos en el CPNP, tiene la opci\u00f3n de hacerlo usted mismo y registrar sus productos bajo nuestros productos, o si desea los documentos a nombre de su propia empresa, podemos extrapolar el expediente por usted.<\/p><p><strong>Informe sobre la seguridad de los productos cosm\u00e9ticos CPSR<\/strong><br \/>Nuestros expedientes de cosm\u00e9ticos contienen informaci\u00f3n patentada y listas exactas de ingredientes que no compartimos. Nos complace compartir la mayor\u00eda de los documentos para el cumplimiento de la normativa local. Si necesita acceder al Informe sobre la seguridad de los productos cosm\u00e9ticos, le pediremos que firme un acuerdo de confidencialidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15b63fe elementor-widget elementor-widget-button\" data-id=\"15b63fe\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#qualitycompliancetop\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-up\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver arriba<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-abfd131 elementor-widget elementor-widget-menu-anchor\" data-id=\"abfd131\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"organic\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c64a8c3 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c64a8c3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ff4de88\" data-id=\"ff4de88\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3743501 elementor-widget elementor-widget-heading\" data-id=\"3743501\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Productos ecol\u00f3gicos certificados<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d269f63 elementor-widget elementor-widget-heading\" data-id=\"d269f63\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Certificaci\u00f3n ecol\u00f3gica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad264a9 elementor-widget elementor-widget-text-editor\" data-id=\"ad264a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>C\u00e1\u00f1amo ecol\u00f3gico certificado<\/strong><br \/>Mantenemos estrechas relaciones con cultivadores de c\u00e1\u00f1amo ecol\u00f3gico en Croacia, donde se encuentra nuestra producci\u00f3n principal. Nuestro c\u00e1\u00f1amo europeo utilizado para la producci\u00f3n de CBD se cultiva bajo certificaci\u00f3n org\u00e1nica.<\/p><p><strong>Productos de CBD ecol\u00f3gicos certificados<\/strong><br \/>Anteriormente hemos sido certificados por <a href=\"https:\/\/www.skal.nl\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Bioinspecci\u00f3n SKAL<\/span><\/a>, la agencia neerlandesa que regula el logotipo de \"certificaci\u00f3n ecol\u00f3gica\". Recientemente se retir\u00f3 esta certificaci\u00f3n debido a su <a href=\"https:\/\/www.skal.nl\/nieuws\/cbd-voldoet-niet-aan-eu-bio-verordening\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">cambio de posici\u00f3n con respecto al CBD<\/span><\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbc437c elementor-widget elementor-widget-button\" data-id=\"dbc437c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#qualitycompliancetop\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-up\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver arriba<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-151774d\" data-id=\"151774d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68f9d5d elementor-widget elementor-widget-image\" data-id=\"68f9d5d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EIHA-v1-1.webp\" class=\"attachment-large size-large wp-image-130\" alt=\"\" srcset=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EIHA-v1-1.webp 400w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EIHA-v1-1-300x300.webp 300w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EIHA-v1-1-150x150.webp 150w, https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-EIHA-v1-1-100x100.webp 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Calidad y conformidad Gesti\u00f3n de la calidad Altos est\u00e1ndares de calidad Navegue r\u00e1pidamente a: GMP, ISO, HACCP Pruebas de laboratorio propias y de terceros Documentaci\u00f3n de calidad CPNP y CPSR Cosm\u00e9ticos Certificaci\u00f3n ecol\u00f3gica Certificaci\u00f3n de calidad GMP, ISO, HACCP Nuestra planta de producci\u00f3n croata cuenta con las certificaciones GMP Codex Alimentarius, ISO 9001:2015 y HACCP, as\u00ed como la ISO 22716-2007 de cosm\u00e9ticos. Nuestra [...]<\/p>","protected":false},"author":1,"featured_media":0,"parent":1329,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-1504","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.2 (Yoast SEO v23.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quality &amp; compliance - CBD Oil Europe<\/title>\n<meta name=\"description\" content=\"CBD Oil Europe specialises in white &amp; private label CBD. Wholesale CBD Oil, gummies, cosmetics, pet products, water soluble and distillate and isolate.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbdoileurope.com\/es\/acerca-de\/calidad-y-conformidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quality &amp; compliance\" \/>\n<meta property=\"og:description\" content=\"CBD Oil Europe specialises in white &amp; private label CBD. Wholesale CBD Oil, gummies, cosmetics, pet products, water soluble and distillate and isolate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbdoileurope.com\/es\/acerca-de\/calidad-y-conformidad\/\" \/>\n<meta property=\"og:site_name\" content=\"CBD Oil Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-22T12:43:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/\",\"url\":\"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/\",\"name\":\"Quality & compliance - CBD Oil Europe\",\"isPartOf\":{\"@id\":\"https:\/\/cbdoileurope.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1.webp\",\"datePublished\":\"2024-03-14T14:24:17+00:00\",\"dateModified\":\"2024-08-22T12:43:44+00:00\",\"description\":\"CBD Oil Europe specialises in white & private label CBD. Wholesale CBD Oil, gummies, cosmetics, pet products, water soluble and distillate and isolate.\",\"breadcrumb\":{\"@id\":\"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/#primaryimage\",\"url\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1.webp\",\"contentUrl\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cbdoileurope.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About\",\"item\":\"https:\/\/cbdoileurope.com\/about\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quality &#038; compliance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cbdoileurope.com\/#website\",\"url\":\"https:\/\/cbdoileurope.com\/\",\"name\":\"CBD Oil Europe\",\"description\":\"Simplifying CBD\",\"publisher\":{\"@id\":\"https:\/\/cbdoileurope.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cbdoileurope.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cbdoileurope.com\/#organization\",\"name\":\"CBD Oil Europe\",\"url\":\"https:\/\/cbdoileurope.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg\",\"contentUrl\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg\",\"width\":432,\"height\":169,\"caption\":\"CBD Oil Europe\"},\"image\":{\"@id\":\"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/78547167\/\"],\"description\":\"CBD Oil Europe specialises in white label, private label and wholesale CBD products & services. Our product offering includes oil blends, gummies, capsules, cosmetics, pet products, water solubles and CBD extracts such as distillate and isolate. All of our research & development, packaging, label design and fulfilment services are done in-house by the members of our passionate and competent team. Founder and director Adriaan de Kroo started at the bottom of the non-existing CBD industry in 2013, helping other startups with sales and consultancy around this relatively new compound. He represented several of the biggest CBD producers and traders at more than 35 trade shows, from Sevilla to Moscow.\",\"email\":\"info@cbdoileurope.com\",\"telephone\":\"+31640690002\",\"legalName\":\"CBD Oil Europe\",\"foundingDate\":\"2013-06-02\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quality & compliance - CBD Oil Europe","description":"CBD Oil Europe specialises in white & private label CBD. Wholesale CBD Oil, gummies, cosmetics, pet products, water soluble and distillate and isolate.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbdoileurope.com\/es\/acerca-de\/calidad-y-conformidad\/","og_locale":"es_ES","og_type":"article","og_title":"Quality & compliance","og_description":"CBD Oil Europe specialises in white & private label CBD. Wholesale CBD Oil, gummies, cosmetics, pet products, water soluble and distillate and isolate.","og_url":"https:\/\/cbdoileurope.com\/es\/acerca-de\/calidad-y-conformidad\/","og_site_name":"CBD Oil Europe","article_modified_time":"2024-08-22T12:43:44+00:00","og_image":[{"url":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1.webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/","url":"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/","name":"Quality & compliance - CBD Oil Europe","isPartOf":{"@id":"https:\/\/cbdoileurope.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/#primaryimage"},"image":{"@id":"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/#primaryimage"},"thumbnailUrl":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1.webp","datePublished":"2024-03-14T14:24:17+00:00","dateModified":"2024-08-22T12:43:44+00:00","description":"CBD Oil Europe specialises in white & private label CBD. Wholesale CBD Oil, gummies, cosmetics, pet products, water soluble and distillate and isolate.","breadcrumb":{"@id":"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/#primaryimage","url":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1.webp","contentUrl":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Quality-ISO-v1-1.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/cbdoileurope.com\/about\/quality-and-compliance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbdoileurope.com\/"},{"@type":"ListItem","position":2,"name":"About","item":"https:\/\/cbdoileurope.com\/about\/"},{"@type":"ListItem","position":3,"name":"Quality &#038; compliance"}]},{"@type":"WebSite","@id":"https:\/\/cbdoileurope.com\/#website","url":"https:\/\/cbdoileurope.com\/","name":"CBD Oil Europe","description":"Simplifying CBD","publisher":{"@id":"https:\/\/cbdoileurope.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbdoileurope.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cbdoileurope.com\/#organization","name":"CBD Oil Europe","url":"https:\/\/cbdoileurope.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/","url":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg","contentUrl":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg","width":432,"height":169,"caption":"CBD Oil Europe"},"image":{"@id":"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/78547167\/"],"description":"CBD Oil Europe specialises in white label, private label and wholesale CBD products & services. Our product offering includes oil blends, gummies, capsules, cosmetics, pet products, water solubles and CBD extracts such as distillate and isolate. All of our research & development, packaging, label design and fulfilment services are done in-house by the members of our passionate and competent team. Founder and director Adriaan de Kroo started at the bottom of the non-existing CBD industry in 2013, helping other startups with sales and consultancy around this relatively new compound. He represented several of the biggest CBD producers and traders at more than 35 trade shows, from Sevilla to Moscow.","email":"info@cbdoileurope.com","telephone":"+31640690002","legalName":"CBD Oil Europe","foundingDate":"2013-06-02"}]}},"_links":{"self":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/pages\/1504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/comments?post=1504"}],"version-history":[{"count":372,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/pages\/1504\/revisions"}],"predecessor-version":[{"id":18313,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/pages\/1504\/revisions\/18313"}],"up":[{"embeddable":true,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/pages\/1329"}],"wp:attachment":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/media?parent=1504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}