{"id":7991,"date":"2023-09-19T11:39:09","date_gmt":"2023-09-19T11:39:09","guid":{"rendered":"https:\/\/cbdoileurope.com\/?post_type=docs&#038;p=7991"},"modified":"2023-10-25T10:20:06","modified_gmt":"2023-10-25T10:20:06","password":"","slug":"can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil","status":"publish","type":"docs","link":"https:\/\/cbdoileurope.com\/es\/docs\/puedo-registrar-un-producto-como-cosmetico-si-contiene-terpenos-de-canamo-aceite-de-limon-o-aceite-de-menta\/","title":{"rendered":"\u00bfPuedo registrar un producto como cosm\u00e9tico si contiene terpenos de c\u00e1\u00f1amo, aceite de lim\u00f3n o aceite de menta?"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Limoneno en cosm\u00e9ticos Productos CBD<\/h2>\n\n\n\n<p>El limoneno es un terpeno com\u00fan presente en los extractos de c\u00e1\u00f1amo, tambi\u00e9n puede encontrarse si su producto contiene terpenos de c\u00e1\u00f1amo a\u00f1adidos u otros aromatizantes.<\/p>\n\n\n\n<p>Es necesario indicar claramente en la etiqueta la presencia de limoneno y que determinadas personas al\u00e9rgicas o con piel sensible deben evitarlo.&nbsp;<\/p>\n\n\n\n<p>Nuestros asesores cosm\u00e9ticos nos han aconsejado no registrar como cosm\u00e9ticos productos que contengan terpenos de c\u00e1\u00f1amo debido a su complejidad y a los riesgos a los que te expones si alguna vez te controlan las autoridades cosm\u00e9ticas.&nbsp;<\/p>\n\n\n\n<p><strong>26 al\u00e9rgenos conocidos en los cosm\u00e9ticos<\/strong><\/p>\n\n\n\n<p>El Reglamento 1223\/2009 sobre cosm\u00e9ticos enumera las 26 sustancias alerg\u00e9nicas m\u00e1s conocidas. Estas sustancias deben aparecer en la etiqueta de su producto cosm\u00e9tico cuando est\u00e9n presentes en la f\u00f3rmula acabada en determinados umbrales.<\/p>\n\n\n\n<p>Si una de las 26 sustancias enumeradas en la&nbsp; <a href=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2021\/10\/26-Known-Allergens-in-Cosmetics.pdf\">26 al\u00e9rgenos conocidos en los cosm\u00e9ticos<\/a>&nbsp;est\u00e1 presente en su f\u00f3rmula acabada, tiene que cumplir los requisitos de etiquetado del Reglamento europeo. Debe cumplir las siguientes normas:<\/p>\n\n\n\n<p>Las sustancias alerg\u00e9nicas deben figurar en la etiqueta si:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La concentraci\u00f3n es superior a 0,01% en un producto que se aclara, por ejemplo, un champ\u00fa.<\/li>\n\n\n\n<li>La concentraci\u00f3n es superior a 0,001% en un producto sin aclarado, por ejemplo, una crema de noche.<\/li>\n<\/ul>\n\n\n\n<p>Nota: Si un al\u00e9rgeno est\u00e1 contenido en diferentes ingredientes de su producto, tiene que sumar todas las concentraciones para verificar el umbral y etiquetar su producto de acuerdo con la norma anterior.<\/p>\n\n\n\n<p>Adem\u00e1s de estos requisitos espec\u00edficos, debe cumplir todos los requisitos establecidos por el Reglamento sobre cosm\u00e9ticos, especialmente los relativos al etiquetado.<\/p>\n\n\n\n<p><strong><em>Para garantizar que los consumidores est\u00e9n adecuadamente informados, la presencia de estas sustancias debe mencionarse en la lista de ingredientes y debe llamarse la atenci\u00f3n de los consumidores sobre la presencia de estos ingredientes. Esta informaci\u00f3n deber\u00eda mejorar el diagn\u00f3stico de las alergias de contacto entre los consumidores y permitirles evitar el uso de productos cosm\u00e9ticos que no toleran.<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.ecomundo.eu\/en\/blog\/cosmetics-allergens-europe-compliance\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Limoneno en Terpenos y Aceite de lim\u00f3n \/ menta piperita<\/h2>\n\n\n\n<p>A\u00f1adimos terpenos de c\u00e1\u00f1amo, aceite de lim\u00f3n y menta a algunos de nuestros complementos alimenticios. Debe tener en cuenta que si se registran como cosm\u00e9ticos contendr\u00e1n Limoneno&nbsp;&nbsp;<\/p>\n\n\n\n<p>El limoneno es un constituyente qu\u00edmico de muchos ingredientes arom\u00e1ticos naturales, sobre todo de aceites de c\u00edtricos como el lim\u00f3n (d-limoneno) y de pinos o especies de la familia de la menta (l-limoneno).&nbsp;<\/p>\n\n\n\n<p>Como la mayor\u00eda de los componentes vol\u00e1tiles de las fragancias, el limoneno tambi\u00e9n tiene grandes beneficios antioxidantes y se ha demostrado que calma la piel; sin embargo, cuando se exponen al aire, estos compuestos antioxidantes altamente vol\u00e1tiles se oxidan y pueden sensibilizar la piel.<\/p>\n\n\n\n<p>Seg\u00fan una evaluaci\u00f3n de seguridad de 2013 publicada en el Journal of Toxicology and Environmental Health, se notific\u00f3 irritaci\u00f3n cut\u00e1nea o potencial sensibilizante tras el uso de este agente en diversos productos. En animales de experimentaci\u00f3n y seres humanos, se demostr\u00f3 que los subproductos del d-limoneno act\u00faan como irritantes cut\u00e1neos. Aparte de la irritaci\u00f3n y la sensibilidad, no se observaron otros problemas como toxicidad o carcinogenicidad. Bas\u00e1ndose en esta informaci\u00f3n, se suele recomendar a las personas con piel sensible o afecciones cut\u00e1neas como eczema, psoriasis o ros\u00e1cea que eviten los productos que contengan limoneno.<\/p>","protected":false},"excerpt":{"rendered":"<p>Limonene in cosmetics CBD products Limonene is a common terpene present in hemp extracts, it can also be found if your product contains added hemp terpenes or other flavourings. You need to clearly state on the label the presence of Limonene and that certain people with allergies or sensitive skin should avoid it.&nbsp; Our cosmetics [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"doc_category":[39],"doc_tag":[],"class_list":["post-7991","docs","type-docs","status-publish","hentry","doc_category-cosmetics"],"acf":[],"year_month":"2026-05","word_count":512,"total_views":"1871","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Laurens van Dijk","author_nicename":"laurenscbdoileurope-com","author_url":"https:\/\/cbdoileurope.com\/es\/author\/laurenscbdoileurope-com\/"},"doc_category_info":[{"term_name":"Cosmetics","term_url":"https:\/\/cbdoileurope.com\/es\/docs-category\/cosmeticos\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.2 (Yoast SEO v23.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Can I register a product as a cosmetic if it contains hemp terpenes, lemon oil or peppermint oil? - CBD Oil Europe<\/title>\n<meta name=\"description\" content=\"Find answers to your CBD wholesale questions. Learn about white label, private label, and bulk CBD products. Our documentation covers everything from product details to order processes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbdoileurope.com\/es\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Can I register a product as a cosmetic if it contains hemp terpenes, lemon oil or peppermint oil?\" \/>\n<meta property=\"og:description\" content=\"Find answers to your CBD wholesale questions. Learn about white label, private label, and bulk CBD products. Our documentation covers everything from product details to order processes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbdoileurope.com\/es\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/\" \/>\n<meta property=\"og:site_name\" content=\"CBD Oil Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T10:20:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Images-Home-01-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cbdoileurope.com\/de\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/\",\"url\":\"https:\/\/cbdoileurope.com\/de\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/\",\"name\":\"Can I register a product as a cosmetic if it contains hemp terpenes, lemon oil or peppermint oil? - CBD Oil Europe\",\"isPartOf\":{\"@id\":\"https:\/\/cbdoileurope.com\/#website\"},\"datePublished\":\"2023-09-19T11:39:09+00:00\",\"dateModified\":\"2023-10-25T10:20:06+00:00\",\"description\":\"Find answers to your CBD wholesale questions. Learn about white label, private label, and bulk CBD products. Our documentation covers everything from product details to order processes.\",\"breadcrumb\":{\"@id\":\"https:\/\/cbdoileurope.com\/de\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cbdoileurope.com\/de\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cbdoileurope.com\/de\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cbdoileurope.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/cbdoileurope.com\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Can I register a product as a cosmetic if it contains hemp terpenes, lemon oil or peppermint oil?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cbdoileurope.com\/#website\",\"url\":\"https:\/\/cbdoileurope.com\/\",\"name\":\"CBD Oil Europe\",\"description\":\"Simplifying CBD\",\"publisher\":{\"@id\":\"https:\/\/cbdoileurope.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cbdoileurope.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cbdoileurope.com\/#organization\",\"name\":\"CBD Oil Europe\",\"url\":\"https:\/\/cbdoileurope.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg\",\"contentUrl\":\"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg\",\"width\":432,\"height\":169,\"caption\":\"CBD Oil Europe\"},\"image\":{\"@id\":\"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/78547167\/\"],\"description\":\"CBD Oil Europe specialises in white label, private label and wholesale CBD products & services. Our product offering includes oil blends, gummies, capsules, cosmetics, pet products, water solubles and CBD extracts such as distillate and isolate. All of our research & development, packaging, label design and fulfilment services are done in-house by the members of our passionate and competent team. Founder and director Adriaan de Kroo started at the bottom of the non-existing CBD industry in 2013, helping other startups with sales and consultancy around this relatively new compound. He represented several of the biggest CBD producers and traders at more than 35 trade shows, from Sevilla to Moscow.\",\"email\":\"info@cbdoileurope.com\",\"telephone\":\"+31640690002\",\"legalName\":\"CBD Oil Europe\",\"foundingDate\":\"2013-06-02\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Can I register a product as a cosmetic if it contains hemp terpenes, lemon oil or peppermint oil? - CBD Oil Europe","description":"Find answers to your CBD wholesale questions. Learn about white label, private label, and bulk CBD products. Our documentation covers everything from product details to order processes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbdoileurope.com\/es\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/","og_locale":"es_ES","og_type":"article","og_title":"Can I register a product as a cosmetic if it contains hemp terpenes, lemon oil or peppermint oil?","og_description":"Find answers to your CBD wholesale questions. Learn about white label, private label, and bulk CBD products. Our documentation covers everything from product details to order processes.","og_url":"https:\/\/cbdoileurope.com\/es\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/","og_site_name":"CBD Oil Europe","article_modified_time":"2023-10-25T10:20:06+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Images-Home-01-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cbdoileurope.com\/de\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/","url":"https:\/\/cbdoileurope.com\/de\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/","name":"Can I register a product as a cosmetic if it contains hemp terpenes, lemon oil or peppermint oil? - CBD Oil Europe","isPartOf":{"@id":"https:\/\/cbdoileurope.com\/#website"},"datePublished":"2023-09-19T11:39:09+00:00","dateModified":"2023-10-25T10:20:06+00:00","description":"Find answers to your CBD wholesale questions. Learn about white label, private label, and bulk CBD products. Our documentation covers everything from product details to order processes.","breadcrumb":{"@id":"https:\/\/cbdoileurope.com\/de\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbdoileurope.com\/de\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cbdoileurope.com\/de\/docs\/can-i-register-a-product-as-a-cosmetic-if-it-contains-hemp-terpenes-lemon-oil-or-peppermint-oil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cbdoileurope.com\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/cbdoileurope.com\/docs\/"},{"@type":"ListItem","position":3,"name":"Can I register a product as a cosmetic if it contains hemp terpenes, lemon oil or peppermint oil?"}]},{"@type":"WebSite","@id":"https:\/\/cbdoileurope.com\/#website","url":"https:\/\/cbdoileurope.com\/","name":"CBD Oil Europe","description":"Simplifying CBD","publisher":{"@id":"https:\/\/cbdoileurope.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbdoileurope.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cbdoileurope.com\/#organization","name":"CBD Oil Europe","url":"https:\/\/cbdoileurope.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/","url":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg","contentUrl":"https:\/\/cbdoileurope.com\/wp-content\/uploads\/2022\/11\/CBDEU-Logo-RGB-Horizontal-1.svg","width":432,"height":169,"caption":"CBD Oil Europe"},"image":{"@id":"https:\/\/cbdoileurope.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/78547167\/"],"description":"CBD Oil Europe specialises in white label, private label and wholesale CBD products & services. Our product offering includes oil blends, gummies, capsules, cosmetics, pet products, water solubles and CBD extracts such as distillate and isolate. All of our research & development, packaging, label design and fulfilment services are done in-house by the members of our passionate and competent team. Founder and director Adriaan de Kroo started at the bottom of the non-existing CBD industry in 2013, helping other startups with sales and consultancy around this relatively new compound. He represented several of the biggest CBD producers and traders at more than 35 trade shows, from Sevilla to Moscow.","email":"info@cbdoileurope.com","telephone":"+31640690002","legalName":"CBD Oil Europe","foundingDate":"2013-06-02"}]}},"_links":{"self":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/docs\/7991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/comments?post=7991"}],"version-history":[{"count":1,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/docs\/7991\/revisions"}],"predecessor-version":[{"id":7992,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/docs\/7991\/revisions\/7992"}],"wp:attachment":[{"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/media?parent=7991"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/doc_category?post=7991"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/cbdoileurope.com\/es\/wp-json\/wp\/v2\/doc_tag?post=7991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}